{"id":38,"date":"2021-10-01T11:45:54","date_gmt":"2021-10-01T09:45:54","guid":{"rendered":"https:\/\/einstein-website.de\/en\/wp-content\/uploads\/sites\/2\/2021\/10\/15_AE_credo_p1-1.jpeg"},"modified":"2021-10-01T11:45:54","modified_gmt":"2021-10-01T09:45:54","slug":"15_ae_credo_p1-1-2","status":"inherit","type":"attachment","link":"https:\/\/einstein-website.de\/en\/15_ae_credo_p1-1-2\/","title":{"rendered":"15_AE_credo_p1-1"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-38","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/einstein-website.de\/en\/wp-content\/uploads\/sites\/2\/2021\/10\/15_AE_credo_p1-1.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"235\" height=\"300\" src=\"https:\/\/einstein-website.de\/en\/wp-content\/uploads\/sites\/2\/2021\/10\/15_AE_credo_p1-1-235x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/einstein-website.de\/en\/wp-content\/uploads\/sites\/2\/2021\/10\/15_AE_credo_p1-1-235x300.jpeg 235w, https:\/\/einstein-website.de\/en\/wp-content\/uploads\/sites\/2\/2021\/10\/15_AE_credo_p1-1.jpeg 365w\" sizes=\"(max-width: 235px) 100vw, 235px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":365,"height":465,"file":"2021\/10\/15_AE_credo_p1-1.jpeg","filesize":110265,"sizes":{"medium":{"file":"15_AE_credo_p1-1-235x300.jpeg","width":235,"height":300,"filesize":21697,"mime_type":"image\/jpeg","source_url":"https:\/\/einstein-website.de\/en\/wp-content\/uploads\/sites\/2\/2021\/10\/15_AE_credo_p1-1-235x300.jpeg"},"thumbnail":{"file":"15_AE_credo_p1-1-150x150.jpeg","width":150,"height":150,"filesize":15155,"mime_type":"image\/jpeg","source_url":"https:\/\/einstein-website.de\/en\/wp-content\/uploads\/sites\/2\/2021\/10\/15_AE_credo_p1-1-150x150.jpeg"},"full":{"file":"15_AE_credo_p1-1.jpeg","width":365,"height":465,"mime_type":"image\/jpeg","source_url":"https:\/\/einstein-website.de\/en\/wp-content\/uploads\/sites\/2\/2021\/10\/15_AE_credo_p1-1.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/einstein-website.de\/en\/wp-content\/uploads\/sites\/2\/2021\/10\/15_AE_credo_p1-1.jpeg","_links":{"self":[{"href":"https:\/\/einstein-website.de\/en\/wp-json\/wp\/v2\/media\/38"}],"collection":[{"href":"https:\/\/einstein-website.de\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/einstein-website.de\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/einstein-website.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/einstein-website.de\/en\/wp-json\/wp\/v2\/comments?post=38"}]}}